{"id":1394,"date":"2025-03-13T19:00:32","date_gmt":"2025-03-13T18:00:32","guid":{"rendered":"https:\/\/dolcemassages.com\/cookies-politik\/"},"modified":"2025-09-13T18:05:48","modified_gmt":"2025-09-13T17:05:48","slug":"cookies-politik","status":"publish","type":"page","link":"https:\/\/dolcemassages.com\/de\/cookies-politik\/","title":{"rendered":"Cookies Politik"},"content":{"rendered":"\n<!-- Legal document generated by Complianz | GDPR\/CCPA Cookie Consent https:\/\/wordpress.org\/plugins\/complianz-gdpr -->\n<div id=\"cmplz-document\" class=\"cmplz-document cookie-statement cmplz-document-eu\"><p><i>Diese Cookie-Richtlinie wurde zuletzt am September 13, 2025 aktualisiert und gilt f\u00fcr B\u00fcrger und Einwohner mit st\u00e4ndigem Wohnsitz im Europ\u00e4ischen Wirtschaftsraum und der Schweiz.<\/i><br><\/p><h2>1. Einleitung<\/h2><p>Unsere Website, <a href=\"https:\/\/dolcemassages.com\/de\/\">https:\/\/dolcemassages.com\/de\/<\/a> (im folgenden: &#8222;Die Website&#8220;) verwendet Cookies und \u00e4hnliche Technologien (der Einfachheit halber werden all diese unter &#8222;Cookies&#8220; zusammengefasst). Cookies werden au\u00dferdem von uns beauftragten Drittparteien platziert. In dem unten stehenden Dokument informieren wir dich \u00fcber die Verwendung von Cookies auf unserer Website.<\/p><h2>2. Was sind Cookies?<\/h2><p>Ein Cookie ist eine einfache kleine Datei, die gemeinsam mit den Seiten einer Internetadresse versendet und vom Webbrowser auf dem PC oder einem anderen Ger\u00e4t gespeichert werden kann. Die darin gespeicherten Informationen k\u00f6nnen w\u00e4hrend folgender Besuche zu unseren oder den Servern relevanter Drittanbieter gesendet werden.<\/p><h2>3. Was sind Skripte?<\/h2><p>Ein Script ist ein St\u00fcck Programmcode, das benutzt wird, um unserer Website Funktionalit\u00e4t und Interaktivit\u00e4t zu erm\u00f6glichen. Dieser Code wird auf unseren Servern oder auf deinem Ger\u00e4t ausgef\u00fchrt.<\/p><h2>4. Was ist ein Web Beacon?<\/h2><p>Ein Web-Beacon (auch Pixel-Tag genannt), ist ein kleines unsichtbares Textfragment oder Bild auf einer Website, das benutzt wird, um den Verkehr auf der Website zu \u00fcberwachen. Um dies zu erm\u00f6glichen werden diverse Daten von dir mittels Web-Beacons gespeichert.<\/p><h2>5. Cookies<\/h2><p class=\"cmplz-subtitle\">5.1 Technische oder funktionelle Cookies<\/p><p>Einige Cookies stellen sicher, dass Teile unserer Website richtig funktionieren und deine Nutzervorlieben bekannt bleiben. Durch das Platzieren funktionaler Cookies machen wir es dir einfacher unsere Website zu besuchen. Auf diese Weise musst du bei Besuchen unserer Website nicht wiederholt die gleichen Informationen eingeben, oder deine Gegenst\u00e4nde bleiben beispielsweise in deinem Warenkorb bis du bezahlst. Wir k\u00f6nnen diese Cookies ohne dein Einverst\u00e4ndnis platzieren.<\/p><p class=\"cmplz-subtitle\">5.2 Statistik-Cookies<\/p><p>Wir verwenden Statistik-Cookies, um das Website-Erlebnis f\u00fcr unsere Nutzer zu optimieren. Mit diesen Statistik-Cookies erhalten wir Einblicke in die Nutzung unserer Website.&nbsp;Wir bitten um deine Erlaubnis Statistik-Cookies zu setzen.<\/p><h2>6. Platzierte Cookies<\/h2><div id=\"cmplz-cookies-overview\"><details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google reCAPTCHA<\/h3>\n\t\t<p>Funktional, Marketing<\/p>\n\t\t<label for=\"cmplz_service_google-recaptcha\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-recaptcha<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-recaptcha\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-recaptcha\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Verwendung<\/h4>\n\t\t<p>Wir verwenden Google reCAPTCHA f\u00fcr Spam-Vorbeugung.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>F\u00fcr weitere Informationen, bitte die <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">Google reCAPTCHA Datenschutzerkl\u00e4rung<\/a> lesen.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funktional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">_grecaptcha<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">6 Monate<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Spamschutz anbieten<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">rc::c<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">Sitzung<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Anfragen von Bots lesen und filtern<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">rc::b<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">Sitzung<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Anfragen von Bots lesen und filtern<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">rc::a<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">best\u00e4ndig<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Anfragen von Bots lesen und filtern<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WordPress<\/h3>\n\t\t<p>Funktional<\/p>\n\t\t<label for=\"cmplz_service_wordpress\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wordpress<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wordpress\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wordpress\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Verwendung<\/h4>\n\t\t<p>Wir verwenden WordPress f\u00fcr Website-Entwicklung.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>Diese Daten werden nicht an Dritte weitergegeben.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funktional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">wpEmojiSettingsSupports<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">Sitzung<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Speichere Browser-Angaben<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">wp-settings-*<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">best\u00e4ndig<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Speicher die Benutzervorlieben<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">wp-settings-time-*<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">1 Jahr<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Speicher die Benutzervorlieben<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">wordpress_test_cookie<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">Sitzung<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">\u00fcberpr\u00fcft, ob Cookies gesetzt werden k\u00f6nnen<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">wordpress_logged_in_*<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">best\u00e4ndig<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Benutzer eingeloggt lassen<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">wp_lang<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">Sitzung<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Speichere Spracheinstellungen<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Analytics<\/h3>\n\t\t<p>Statistik<\/p>\n\t\t<label for=\"cmplz_service_google-analytics\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-analytics<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-analytics\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-analytics\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Verwendung<\/h4>\n\t\t<p>Wir verwenden Google Analytics f\u00fcr Website-Statistik.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>F\u00fcr weitere Informationen, bitte die <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/business.safety.google\/privacy\/\">Google Analytics Datenschutzerkl\u00e4rung<\/a> lesen.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Statistik<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">_ga<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">2 Jahre<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Z\u00e4hlt und verfolgt Seitenaufrufe<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">_ga_*<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">1 Jahr<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Z\u00e4hlt und verfolgt Seitenaufrufe<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Matomo<\/h3>\n\t\t<p>Statistik (anonym)<\/p>\n\t\t<label for=\"cmplz_service_matomo\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service matomo<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_matomo\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"matomo\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Verwendung<\/h4>\n\t\t<p>Wir verwenden Matomo f\u00fcr Website-Statistik.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>Diese Daten werden nicht an Dritte weitergegeben.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Statistik (anonym)<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">_pk_id*<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">13 Monate<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Speichere die eindeutige User-ID<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">_pk_ref*<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">6 Monate<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Speichere die \u00dcbergabe-ID<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WPML<\/h3>\n\t\t<p>Funktional<\/p>\n\t\t<label for=\"cmplz_service_wpml\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wpml<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wpml\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wpml\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Verwendung<\/h4>\n\t\t<p>Wir verwenden WPML f\u00fcr Verwaltung der Gebietsschemen.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>Diese Daten werden nicht an Dritte weitergegeben.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funktional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">wp-wpml_current_language<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">1 Tag<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Speichere Spracheinstellungen<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Fonts<\/h3>\n\t\t<p>Marketing<\/p>\n\t\t<label for=\"cmplz_service_google-fonts\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-fonts<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-fonts\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-fonts\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Verwendung<\/h4>\n\t\t<p>Wir verwenden Google Fonts f\u00fcr Anzeige von Webfonts.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>F\u00fcr weitere Informationen, bitte die <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">Google Fonts Datenschutzerkl\u00e4rung<\/a> lesen.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">Google Fonts API<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">keins<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Fordere die Benutzer-IP-Adresse an<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Maps<\/h3>\n\t\t<p>Marketing<\/p>\n\t\t<label for=\"cmplz_service_google-maps\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-maps<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-maps\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-maps\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Verwendung<\/h4>\n\t\t<p>Wir verwenden Google Maps f\u00fcr Kartenanzeige.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>F\u00fcr weitere Informationen, bitte die <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/business.safety.google\/privacy\/\">Google Maps Datenschutzerkl\u00e4rung<\/a> lesen.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">Google Maps API<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">keins<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Fordere die Benutzer-IP-Adresse an<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Complianz<\/h3>\n\t\t<p>Funktional<\/p>\n\t\t<label for=\"cmplz_service_complianz\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service complianz<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_complianz\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"complianz\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Verwendung<\/h4>\n\t\t<p>Wir verwenden Complianz f\u00fcr Verwaltung der Cookie-Einwilligung.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>Diese Daten werden nicht an Dritte weitergegeben.&nbsp;F\u00fcr weitere Informationen, bitte die <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/complianz.io\/legal\/privacy-statement\/\">Complianz Datenschutzerkl\u00e4rung<\/a> lesen.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funktional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_functional<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Speichere Cookie-Einwilligungsvorgaben<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_statistics<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Speichere Cookie-Einwilligungsvorgaben<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_preferences<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Speichere Cookie-Einwilligungsvorgaben<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_marketing<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Speichere Cookie-Einwilligungsvorgaben<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Sonstiges<\/h3>\n\t\t<p>Gegenstand der Untersuchung<\/p>\n\t\t<label for=\"cmplz_service_sonstiges\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service sonstiges<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_sonstiges\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"sonstiges\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Verwendung<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>Die Weitergabe von Daten wird noch untersucht<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Gegenstand der Untersuchung<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">ate-maiya-info_a2ce24ed-3178-4610-a512-0d6b125d1cdf<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">settings-store<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">WP_DATA_USER_3<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">_pk_ref_1_cf20<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cf_*<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">WP_PREFERENCES_USER_1<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">continueReview<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_consented_services<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_saved_services<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_id<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_saved_categories<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_policy_id<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_banner-status<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">age_gate<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_user_data<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">wpseoFrontendInspectorOpen<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">wpml-available-translators-notice-dismissed<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">ate-maiya-info<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">_clck<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">_cltk<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">_pk_ses.2.cf20<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">_clsk<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">_pk_ses_2_cf20<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">_gcl_ls<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<\/div><h2>7. Zustimmung<\/h2><p>Wenn du unsere Website das erste Mal besuchst, zeigen wir dir ein Pop-Up mit einer Erkl\u00e4rung \u00fcber Cookies. Sobald du auf &#8222;Guardar preferencias&#8220; klickst, gibst du uns dein Einverst\u00e4ndnis, alle von dir gew\u00e4hlten Kategorien von Cookies und Plugins wie in dieser Cookie-Richtlinie beschrieben, zu verwenden. Du kannst die Verwendung von Cookies \u00fcber deinen Browser deaktivieren, aber bitte beachte, dass unsere Website dann unter Umst\u00e4nden nicht richtig funktioniert.<\/p><p class=\"cmplz-subtitle\">7.1 Verwalte deine Zustimmungseinstellungen<\/p><div id=\"cmplz-manage-consent-container-nojavascript\">Du hast die Cookie-Richtlinie ohne Javascript-Unterst\u00fctzung geladen.&nbsp;Unter AMP kannst du die Schaltfl\u00e4che zum Zustimmen der Einwilligung unten auf der Seite verwenden.<\/div><div id=\"cmplz-manage-consent-container\" name=\"cmplz-manage-consent-container\" class=\"cmplz-manage-consent-container\"><\/div><h2>8. Aktivierung\/Deaktivierung und L\u00f6schen von Cookies<\/h2><p>Du kannst deinen Internetbrowser verwenden um automatisch oder manuell Cookies zu l\u00f6schen. Du kannst au\u00dferdem spezifizieren, ob spezielle Cookies nicht platziert werden sollen. Eine andere M\u00f6glichkeit ist es, deinen Internetbrowser derart einzurichten, dass du jedes Mal benachrichtigt wirst, wenn ein Cookie platziert wird. F\u00fcr weitere Information \u00fcber diese M\u00f6glichkeiten, beachte die Anweisungen in der Hilfesektion deines Browsers.<\/p><p>Bitte nimm zur Kenntnis, dass unsere Website m\u00f6glicherweise nicht richtig funktioniert, wenn alle Cookies deaktiviert sind. Wenn du die Cookies in deinem Browser l\u00f6scht, werden diese neu platziert, wenn du unsere Website erneut besuchst.<\/p><h2>9. Deine Rechte in Bezug auf pers\u00f6nliche Daten<\/h2><p>Du hast in Bezug auf deine pers\u00f6nlichen Daten die folgenden Rechte:<\/p><ul>\n                    <li>Du hast das Recht zu wissen, warum deine pers\u00f6nlichen Daten gebraucht werden, was mit ihnen passiert und wie lange diese verwahrt werden.<\/li>\n                    <li>Zugriffsrecht: Du hast das Recht, deine uns bekannten pers\u00f6nliche Daten einzusehen.<\/li>\n                    <li>Recht auf Berichtigung: Du hast das Recht, wann immer du w\u00fcnscht, deine pers\u00f6nlichen Daten zu erg\u00e4nzen, zu korrigieren sowie gel\u00f6scht oder blockiert zu bekommen.<\/li>\n                    <li>Wenn du uns dein Einverst\u00e4ndnis zur Verarbeitung deiner Daten gegeben hast, hast du das Recht, dieses Einverst\u00e4ndnis zu widerrufen und deine pers\u00f6nlichen Daten l\u00f6schen zu lassen.<\/li>\n                    <li>Recht auf Datentransfer deiner Daten: Du hast das Recht, alle deine pers\u00f6nlichen Daten von einem Verantwortlichen anzufordern und in ihrer Gesamtheit zu einem anderen Verantwortlichen zu transferieren.<\/li>\n                    <li>Widerspruchsrecht: Du kannst der Verarbeitung deiner Daten widersprechen. Wir entsprechen dem, es sei denn es gibt berechtigte Gr\u00fcnde f\u00fcr die Verarbeitung.<\/li>\n                <\/ul><p>Um diese Rechte auszu\u00fcben kontaktiere uns bitte. Bitte beziehe dich auf die Kontaktdaten am Ende dieser Cookie-Erkl\u00e4rung. Wenn du eine Beschwerde dar\u00fcber hast, wie wir deine Daten behandeln, w\u00fcrden wir diese gerne h\u00f6ren, aber du hast auch das Recht diese an die Aufsichtsbeh\u00f6rde (Datenschutzbeh\u00f6rde) zu richten.<\/p><h2>10. Kontaktdaten<\/h2><p>F\u00fcr Fragen und\/oder Kommentare \u00fcber unsere Cookie-Richtlinien und diese Aussage kontaktiere uns bitte mittels der folgenden Kontaktdaten:<\/p><p><span class=\"cmplz-contact-organisation\">Dolce Massages Barcelona<\/span><br>\n                      <span class=\"cmplz-contact-address\">Gran Via de les corts catalanes 617, 08007 Barcelona<\/span><br>\n                      <span class=\"cmplz-contact-country\">Spanien<\/span><br>\n                    Website: <span class=\"cmplz-contact-domain\"><a href=\"https:\/\/dolcemassages.com\/de\/\">https:\/\/dolcemassages.com\/de\/<\/a><\/span><br>\n                    E-Mail: <span class=\"cmplz-contact-email\"><span class=\"cmplz-obfuscate\">&#103;&#100;rp@<span class=\"cmplz-fmail-domain\">ex&#046;&#099;om<\/span>d&#111;&#108;&#099;e&#109;&#097;&#115;s&#097;ge&#115;.c&#111;&#109;<\/span><\/span><br>\n                    <span class=\"cmplz-contact-telephone\">Telefonnummer: +34 674 47 03 18<\/span><\/p><p>Diese Cookie-Richtlinie wurde mit <a href=\"https:\/\/cookiedatabase.org\/\" target=\"_blank\" rel=\"noopener\">cookiedatabase.org<\/a> am August 29, 2026 synchronisiert.<\/p><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1394","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dolcemassages.com\/de\/wp-json\/wp\/v2\/pages\/1394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dolcemassages.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dolcemassages.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dolcemassages.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dolcemassages.com\/de\/wp-json\/wp\/v2\/comments?post=1394"}],"version-history":[{"count":2,"href":"https:\/\/dolcemassages.com\/de\/wp-json\/wp\/v2\/pages\/1394\/revisions"}],"predecessor-version":[{"id":1952,"href":"https:\/\/dolcemassages.com\/de\/wp-json\/wp\/v2\/pages\/1394\/revisions\/1952"}],"wp:attachment":[{"href":"https:\/\/dolcemassages.com\/de\/wp-json\/wp\/v2\/media?parent=1394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}